{"id":1740,"date":"2022-06-06T21:46:17","date_gmt":"2022-06-06T21:46:17","guid":{"rendered":"https:\/\/dosumaya.com.tr\/habari\/"},"modified":"2022-11-01T19:07:37","modified_gmt":"2022-11-01T19:07:37","slug":"habari","status":"publish","type":"page","link":"https:\/\/dosumaya.com.tr\/sw\/habari\/","title":{"rendered":"Habari"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1740\" class=\"elementor elementor-1740 elementor-237\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a0f1c61 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5a0f1c61\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32a80b4d\" data-id=\"32a80b4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f04ea47 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f04ea47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Habari<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-773ac2fe elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"773ac2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">DOSUMAYA : MBIA WAKO MAHIRI KWA USHINDI<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e16cbbf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e16cbbf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5948788e\" data-id=\"5948788e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629e9bab elementor-widget elementor-widget-spacer\" data-id=\"629e9bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3efff8 elementor-widget elementor-widget-text-editor\" data-id=\"d3efff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gundua habari zetu za hivi punde na matukio hapa. Tutafurahi kushiriki nawe!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfa49e5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfa49e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-167362d\" data-id=\"167362d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e38e836 elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"e38e836\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;2&quot;,&quot;pagination_type&quot;:&quot;load_more_infinite_scroll&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1708 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized-sw\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dosumaya.com.tr\/sw\/djazagro-2022\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"828\" height=\"621\" src=\"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/302065769_1068377684042146_6244896679084705572_n.jpg\" class=\"attachment-full size-full wp-image-1709\" alt=\"\" srcset=\"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/302065769_1068377684042146_6244896679084705572_n.jpg 828w, https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/302065769_1068377684042146_6244896679084705572_n-300x225.jpg 300w, https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/302065769_1068377684042146_6244896679084705572_n-768x576.jpg 768w\" sizes=\"(max-width: 828px) 100vw, 828px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h2 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dosumaya.com.tr\/sw\/djazagro-2022\/\" >\n\t\t\t\tDjazagro 2022\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Timu ya Dosumaya inakualika kukutana nao kwenye stendi yao wakati wa maonyesho ya Djazagro ambayo hufanyika kuanzia Mei 30 hadi Juni 2, 2022.<\/p>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dosumaya.com.tr\/sw\/djazagro-2022\/\" aria-label=\"Read more about Djazagro 2022\" tabindex=\"-1\" >\n\t\t\tSoma zaidi \u2192\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\tJuni 6, 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Habari DOSUMAYA : MBIA WAKO MAHIRI KWA USHINDI Gundua habari zetu za hivi punde na matukio hapa. Tutafurahi kushiriki nawe!<\/p>\n","protected":false},"author":1,"featured_media":1741,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1740","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Habari - DOSUMAYA Istanbul<\/title>\n<meta name=\"description\" content=\"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dosumaya.com.tr\/sw\/habari\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habari - DOSUMAYA Istanbul\" \/>\n<meta property=\"og:description\" content=\"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dosumaya.com.tr\/sw\/habari\/\" \/>\n<meta property=\"og:site_name\" content=\"DOSUMAYA Istanbul\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-01T19:07:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/slider-ok-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/\",\"url\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/\",\"name\":\"Habari - DOSUMAYA Istanbul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dosumaya.com.tr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/slider-ok-1.jpg\",\"datePublished\":\"2022-06-06T21:46:17+00:00\",\"dateModified\":\"2022-11-01T19:07:37+00:00\",\"description\":\"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/#breadcrumb\"},\"inLanguage\":\"sw\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sw\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dosumaya.com.tr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/slider-ok-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dosumaya.com.tr\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/slider-ok-1.jpg\",\"width\":1920,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/habari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#website\",\"url\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/\",\"name\":\"DOSUMAYA Istanbul\",\"description\":\"Istanbul DOSUMaya is a globally operating baking yeast producer\",\"publisher\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sw\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#organization\",\"name\":\"DOSUMAYA Istanbul\",\"url\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sw\",\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dosumaya.com.tr\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/dosu-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/dosumaya.com.tr\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/dosu-logo.jpg\",\"width\":300,\"height\":300,\"caption\":\"DOSUMAYA Istanbul\"},\"image\":{\"@id\":\"https:\\\/\\\/dosumaya.com.tr\\\/sw\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Habari - DOSUMAYA Istanbul","description":"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dosumaya.com.tr\/sw\/habari\/","og_locale":"en_US","og_type":"article","og_title":"Habari - DOSUMAYA Istanbul","og_description":"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!","og_url":"https:\/\/dosumaya.com.tr\/sw\/habari\/","og_site_name":"DOSUMAYA Istanbul","article_modified_time":"2022-11-01T19:07:37+00:00","og_image":[{"width":1920,"height":500,"url":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/slider-ok-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/","url":"https:\/\/dosumaya.com.tr\/sw\/habari\/","name":"Habari - DOSUMAYA Istanbul","isPartOf":{"@id":"https:\/\/dosumaya.com.tr\/sw\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/#primaryimage"},"image":{"@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/#primaryimage"},"thumbnailUrl":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/slider-ok-1.jpg","datePublished":"2022-06-06T21:46:17+00:00","dateModified":"2022-11-01T19:07:37+00:00","description":"Gundua habari na matukio mapya kutoka kwa DOSUMAYA. Tutafurahi kushiriki nawe!","breadcrumb":{"@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/#breadcrumb"},"inLanguage":"sw","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dosumaya.com.tr\/sw\/habari\/"]}]},{"@type":"ImageObject","inLanguage":"sw","@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/#primaryimage","url":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/slider-ok-1.jpg","contentUrl":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/09\/slider-ok-1.jpg","width":1920,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/dosumaya.com.tr\/sw\/habari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dosumaya.com.tr\/sw\/"},{"@type":"ListItem","position":2,"name":"Habari"}]},{"@type":"WebSite","@id":"https:\/\/dosumaya.com.tr\/sw\/#website","url":"https:\/\/dosumaya.com.tr\/sw\/","name":"DOSUMAYA Istanbul","description":"Istanbul DOSUMaya is a globally operating baking yeast producer","publisher":{"@id":"https:\/\/dosumaya.com.tr\/sw\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dosumaya.com.tr\/sw\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sw"},{"@type":"Organization","@id":"https:\/\/dosumaya.com.tr\/sw\/#organization","name":"DOSUMAYA Istanbul","url":"https:\/\/dosumaya.com.tr\/sw\/","logo":{"@type":"ImageObject","inLanguage":"sw","@id":"https:\/\/dosumaya.com.tr\/sw\/#\/schema\/logo\/image\/","url":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/06\/dosu-logo.jpg","contentUrl":"https:\/\/dosumaya.com.tr\/wp-content\/uploads\/2022\/06\/dosu-logo.jpg","width":300,"height":300,"caption":"DOSUMAYA Istanbul"},"image":{"@id":"https:\/\/dosumaya.com.tr\/sw\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/pages\/1740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/comments?post=1740"}],"version-history":[{"count":1,"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/pages\/1740\/revisions"}],"predecessor-version":[{"id":1742,"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/pages\/1740\/revisions\/1742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/media\/1741"}],"wp:attachment":[{"href":"https:\/\/dosumaya.com.tr\/sw\/wp-json\/wp\/v2\/media?parent=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}